{"id":18539,"date":"2024-08-08T13:48:41","date_gmt":"2024-08-08T13:48:41","guid":{"rendered":"https:\/\/livelihoods.eu\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/"},"modified":"2024-08-09T07:03:03","modified_gmt":"2024-08-09T07:03:03","slug":"when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra","status":"publish","type":"post","link":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/","title":{"rendered":"L&rsquo;agroforesterie pour r\u00e9concilier la nature et le caf\u00e9"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d&rsquo;Aceh, situ\u00e9e \u00e0 l&rsquo;extr\u00eame nord de l&rsquo;\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes d\u2019un hectare. Ces exploitations bordent le parc national de Leuser, une zone prot\u00e9g\u00e9e r\u00e9put\u00e9e pour sa biodiversit\u00e9 tropicale, couvrant 9 500 km\u00b2. Cependant, comme d\u2019autres r\u00e9gions d&rsquo;Indon\u00e9sie, le parc national de Leuser subit des pressions dues \u00e0 l&rsquo;expansion des cultures de caf\u00e9 et d&rsquo;autres produits dans les pentes foresti\u00e8res.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une surveillance efficace du parc et une application rigoureuse des lois sont essentielles mais difficiles en raison de l&rsquo;immensit\u00e9 du parc. Pour all\u00e9ger cette pression, une strat\u00e9gie cl\u00e9 est de collaborer avec les communaut\u00e9s locales afin d&rsquo;offrir des sources de revenus alternatives qui n&#8217;empi\u00e8tent pas davantage sur le parc. Cette approche est un objectif central du projet Livelihoods, d\u00e9velopp\u00e9 en partenariat avec la Fondation Leuser, une ONG locale charg\u00e9e de mettre en \u0153uvre les activit\u00e9s du projet.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Revitaliser le caf\u00e9 avec des arbres d\u2019ombrage<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet vise \u00e0 promouvoir des mod\u00e8les de caf\u00e9 r\u00e9silients \u00e0 travers l\u2019agroforesterie et des pratiques agricoles durables pour r\u00e9g\u00e9n\u00e9rer le sol. Pendant des d\u00e9cennies, les agriculteurs ont \u00e9t\u00e9 conseill\u00e9s de cultiver le caf\u00e9 en plein soleil ou avec peu de couverture arbor\u00e9e pour maximiser la production par hectare. Cependant, le caf\u00e9 est une plante foresti\u00e8re qui prosp\u00e8re dans des conditions ombrag\u00e9es, particuli\u00e8rement face aux changements climatiques. L\u2019approche de monoculture a d\u00e9grad\u00e9 la structure du sol, acc\u00e9l\u00e9rant l&rsquo;\u00e9rosion et r\u00e9duisant la mati\u00e8re organique, les engrais chimiques \u00e9tant co\u00fbteux et peu efficaces pour restaurer la biodiversit\u00e9 du sol.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/photo-leuser-1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"436\" height=\"327\" src=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/photo-leuser-1.jpg\" alt=\"\" class=\"wp-image-18530\" srcset=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/photo-leuser-1.jpg 436w, https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/photo-leuser-1-300x225.jpg 300w\" sizes=\"(max-width: 436px) 100vw, 436px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Coffee nurseries, June 2024<\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les petits producteurs reconnaissent de plus en plus la n\u00e9cessit\u00e9 de restaurer des \u00e9cosyst\u00e8mes favorables \u00e0 une production de caf\u00e9 de qualit\u00e9 et de r\u00e9duire les effets du changement climatique, mais manquent souvent des ressources financi\u00e8res et du soutien technique n\u00e9cessaires \u00e0 cette transition. Le projet Livelihoods &#8211; Leuser pr\u00e9voit de r\u00e9pondre \u00e0 ces besoins en plantant 2 millions d\u2019arbres d\u2019ombrage sur 10 000 hectares de parcelles de caf\u00e9 au cours des cinq prochaines ann\u00e9es. <\/p>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\">En plus de fournir de l&rsquo;ombre, les esp\u00e8ces d&rsquo;arbres diversifi\u00e9es offriront des fruits, du bois et du fourrage, b\u00e9n\u00e9ficiant ainsi \u00e0 10 000 familles et g\u00e9n\u00e9rant des revenus suppl\u00e9mentaires gr\u00e2ce \u00e0 la diversification. Les esp\u00e8ces fixatrices d&rsquo;azote am\u00e9lioreront \u00e9galement la fertilit\u00e9 du sol.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Leuser a identifi\u00e9 des volontaires et des parcelles pour la campagne de plantation initiale, qui commencera en septembre, co\u00efncidant avec la saison des pluies. Gr\u00e2ce au financement du Fonds Carbone Livelihoods, les agriculteurs recevront les arbres gratuitement mais devront s&rsquo;engager \u00e0 les entretenir et \u00e0 mettre en \u0153uvre des pratiques agricoles durables, telles que la taille et le compostage. La formation et le coaching des agriculteurs, avec un accent particulier sur les femmes et les jeunes, sont int\u00e9gr\u00e9s au programme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En tout, le projet agroforestier Leuser devrait s\u00e9questrer 1,1 million de tonnes de CO2 sur 20 ans et am\u00e9liorer les conditions de vie de 50 000 personnes. Au-del\u00e0 de s\u00e9questrer du carbone, le projet \u00e9valuera continuellement ses impacts sur la production de caf\u00e9, la restauration de la biodiversit\u00e9 et les revenus des agriculteurs.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-2.jpg\"><img decoding=\"async\" width=\"901\" height=\"827\" src=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-2.jpg\" alt=\"\" class=\"wp-image-18532\" srcset=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-2.jpg 901w, https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-2-300x275.jpg 300w, https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-2-768x705.jpg 768w\" sizes=\"(max-width: 901px) 100vw, 901px\" \/><\/a><figcaption class=\"wp-element-caption\"><em><em>Les Hauts Plateaux de Gayo font partie de l&rsquo;\u00e9cosyst\u00e8me naturel de Leuser, une zone cruciale pour la conservation en raison de sa flore et de sa faune diversifi\u00e9es.<\/em><\/em><\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><a href=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-3.jpg\"><img decoding=\"async\" width=\"915\" height=\"608\" src=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-3.jpg\" alt=\"\" class=\"wp-image-18534\" style=\"width:573px;height:auto\" srcset=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-3.jpg 915w, https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-3-300x199.jpg 300w, https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/leuser-3-768x510.jpg 768w\" sizes=\"(max-width: 915px) 100vw, 915px\" \/><\/a><figcaption class=\"wp-element-caption\"><em>Caf\u00e9 cultiv\u00e9 sous ombrage dans la zone du projet<\/em>.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading has-white-color has-text-color has-background has-link-color wp-elements-9675ac5f0a1bcd06e3ae2d22b8ade489\" style=\"background-color:#008080\"><strong>A propos de la Fondation Leuser<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Leuser est une ONG indon\u00e9sienne de premier plan d\u00e9di\u00e9e \u00e0 la conservation et \u00e0 la gestion durable de l&rsquo;\u00c9cosyst\u00e8me de Leuser dans la province d&rsquo;Aceh, \u00e0 Sumatra. Cr\u00e9\u00e9e en 1999, la fondation se concentre sur la protection et la pr\u00e9servation de l&rsquo;un des derniers vastes \u00e9tendues de for\u00eat tropicale en Asie du Sud-Est, qui abrite une diversit\u00e9 de flore et de faune, y compris des esp\u00e8ces en danger critique comme l\u2019orang-outan de Sumatra, le rhinoc\u00e9ros et le tigre. Gr\u00e2ce \u00e0 son approche globale ax\u00e9e sur l&rsquo;engagement communautaire, la recherche, le plaidoyer et les efforts de conservation, la fondation s\u2019efforce de concilier conservation et d\u00e9veloppement durable.<\/p>\n\n\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background has-link-color wp-element-button\" href=\"https:\/\/leuserfoundation.org\/\" style=\"background-color:#d76616\">En savoir plus sur Leuser<\/a><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d&rsquo;Aceh, situ\u00e9e \u00e0 l&rsquo;extr\u00eame nord de l&rsquo;\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18528,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"iawp_total_views":18,"footnotes":""},"categories":[4],"tags":[5,134,156,187,344,157],"class_list":["post-18539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-agroforestry","tag-biodiversity","tag-farmer-income","tag-impact-investment","tag-livelihoods-carbon-funds","tag-rural-poverty"],"acf":[],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.9 - aioseo.com -->\n\t<meta name=\"description\" content=\"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d&#039;Aceh, situ\u00e9e \u00e0 l&#039;extr\u00eame nord de l&#039;\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Livelihoods\"\/>\n\t<meta name=\"google-site-verification\" content=\"x7TP6hR3xwQedv7TG4cPqKaooosZoM4l7kk4cTzElvY\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.9\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Livelihoods - Building resilient communities &amp; ecosystems alongside sustainable businesses\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods\" \/>\n\t\t<meta property=\"og:description\" content=\"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d&#039;Aceh, situ\u00e9e \u00e0 l&#039;extr\u00eame nord de l&#039;\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-08-08T13:48:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-08-09T07:03:03+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods\" \/>\n\t\t<meta name=\"twitter:description\" content=\"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d&#039;Aceh, situ\u00e9e \u00e0 l&#039;extr\u00eame nord de l&#039;\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#blogposting\",\"name\":\"L\\u2019agroforesterie pour r\\u00e9concilier la nature et le caf\\u00e9 - Livelihoods\",\"headline\":\"L&rsquo;agroforesterie pour r\\u00e9concilier la nature et le caf\\u00e9\",\"author\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/author\\\/livelihoods\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/indonesian-coffee-farmer_root-capital.jpeg\",\"width\":1024,\"height\":683},\"datePublished\":\"2024-08-08T13:48:41+00:00\",\"dateModified\":\"2024-08-09T07:03:03+00:00\",\"inLanguage\":\"fr-FR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#webpage\"},\"articleSection\":\"Blog, Agroforestry, biodiversity, farmer income, impact investment, Livelihoods Carbon Funds, rural poverty, Optional\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/category\\\/blog\\\/#listItem\",\"position\":2,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/livelihoods.eu\\\/category\\\/blog\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#listItem\",\"name\":\"L&rsquo;agroforesterie pour r\\u00e9concilier la nature et le caf\\u00e9\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#listItem\",\"position\":3,\"name\":\"L&rsquo;agroforesterie pour r\\u00e9concilier la nature et le caf\\u00e9\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/category\\\/blog\\\/#listItem\",\"name\":\"Blog\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#organization\",\"name\":\"Livelihoods\",\"description\":\"Building resilient communities & ecosystems alongside sustainable businesses\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#organizationLogo\",\"width\":2983,\"height\":959},\"image\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#organizationLogo\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/author\\\/livelihoods\\\/#author\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/author\\\/livelihoods\\\/\",\"name\":\"Livelihoods\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/20c7160bc30a9a2e291f68312fa2948b00c2bebf2fb91d2d74be5fddf1a3aa27?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Livelihoods\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#webpage\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/\",\"name\":\"L\\u2019agroforesterie pour r\\u00e9concilier la nature et le caf\\u00e9 - Livelihoods\",\"description\":\"En 2024, Livelihoods a lanc\\u00e9 un important projet d\\u2019agroforesterie dans la r\\u00e9gion de Gayo, dans la province d'Aceh, situ\\u00e9e \\u00e0 l'extr\\u00eame nord de l'\\u00eele de Sumatra et qui est reconnue pour sa production de caf\\u00e9 Arabica. Cette r\\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\\u00e9 sur des parcelles moyennes\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/author\\\/livelihoods\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/author\\\/livelihoods\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/indonesian-coffee-farmer_root-capital.jpeg\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#mainImage\",\"width\":1024,\"height\":683},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\\\/#mainImage\"},\"datePublished\":\"2024-08-08T13:48:41+00:00\",\"dateModified\":\"2024-08-09T07:03:03+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/\",\"name\":\"Livelihoods\",\"description\":\"Building resilient communities & ecosystems alongside sustainable businesses\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"https:\\\/\\\/livelihoods.eu\\\/fr\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods","description":"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d'Aceh, situ\u00e9e \u00e0 l'extr\u00eame nord de l'\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes","canonical_url":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"x7TP6hR3xwQedv7TG4cPqKaooosZoM4l7kk4cTzElvY","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#blogposting","name":"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods","headline":"L&rsquo;agroforesterie pour r\u00e9concilier la nature et le caf\u00e9","author":{"@id":"https:\/\/livelihoods.eu\/fr\/author\/livelihoods\/#author"},"publisher":{"@id":"https:\/\/livelihoods.eu\/fr\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/indonesian-coffee-farmer_root-capital.jpeg","width":1024,"height":683},"datePublished":"2024-08-08T13:48:41+00:00","dateModified":"2024-08-09T07:03:03+00:00","inLanguage":"fr-FR","mainEntityOfPage":{"@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#webpage"},"isPartOf":{"@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#webpage"},"articleSection":"Blog, Agroforestry, biodiversity, farmer income, impact investment, Livelihoods Carbon Funds, rural poverty, Optional"},{"@type":"BreadcrumbList","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/fr\/#listItem","position":1,"name":"Home","item":"https:\/\/livelihoods.eu\/fr\/","nextItem":{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/category\/blog\/#listItem","name":"Blog"}},{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/category\/blog\/#listItem","position":2,"name":"Blog","item":"https:\/\/livelihoods.eu\/category\/blog\/","nextItem":{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#listItem","name":"L&rsquo;agroforesterie pour r\u00e9concilier la nature et le caf\u00e9"},"previousItem":{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/fr\/#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#listItem","position":3,"name":"L&rsquo;agroforesterie pour r\u00e9concilier la nature et le caf\u00e9","previousItem":{"@type":"ListItem","@id":"https:\/\/livelihoods.eu\/category\/blog\/#listItem","name":"Blog"}}]},{"@type":"Organization","@id":"https:\/\/livelihoods.eu\/fr\/#organization","name":"Livelihoods","description":"Building resilient communities & ecosystems alongside sustainable businesses","url":"https:\/\/livelihoods.eu\/fr\/","logo":{"@type":"ImageObject","url":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#organizationLogo","width":2983,"height":959},"image":{"@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#organizationLogo"}},{"@type":"Person","@id":"https:\/\/livelihoods.eu\/fr\/author\/livelihoods\/#author","url":"https:\/\/livelihoods.eu\/fr\/author\/livelihoods\/","name":"Livelihoods","image":{"@type":"ImageObject","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/20c7160bc30a9a2e291f68312fa2948b00c2bebf2fb91d2d74be5fddf1a3aa27?s=96&d=mm&r=g","width":96,"height":96,"caption":"Livelihoods"}},{"@type":"WebPage","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#webpage","url":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/","name":"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods","description":"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d'Aceh, situ\u00e9e \u00e0 l'extr\u00eame nord de l'\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes","inLanguage":"fr-FR","isPartOf":{"@id":"https:\/\/livelihoods.eu\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#breadcrumblist"},"author":{"@id":"https:\/\/livelihoods.eu\/fr\/author\/livelihoods\/#author"},"creator":{"@id":"https:\/\/livelihoods.eu\/fr\/author\/livelihoods\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2024\/08\/indonesian-coffee-farmer_root-capital.jpeg","@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#mainImage","width":1024,"height":683},"primaryImageOfPage":{"@id":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/#mainImage"},"datePublished":"2024-08-08T13:48:41+00:00","dateModified":"2024-08-09T07:03:03+00:00"},{"@type":"WebSite","@id":"https:\/\/livelihoods.eu\/fr\/#website","url":"https:\/\/livelihoods.eu\/fr\/","name":"Livelihoods","description":"Building resilient communities & ecosystems alongside sustainable businesses","inLanguage":"fr-FR","publisher":{"@id":"https:\/\/livelihoods.eu\/fr\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Livelihoods - Building resilient communities &amp; ecosystems alongside sustainable businesses","og:type":"article","og:title":"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods","og:description":"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d'Aceh, situ\u00e9e \u00e0 l'extr\u00eame nord de l'\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes","og:url":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/","og:image":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png","og:image:secure_url":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png","article:published_time":"2024-08-08T13:48:41+00:00","article:modified_time":"2024-08-09T07:03:03+00:00","twitter:card":"summary_large_image","twitter:title":"L\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9 - Livelihoods","twitter:description":"En 2024, Livelihoods a lanc\u00e9 un important projet d\u2019agroforesterie dans la r\u00e9gion de Gayo, dans la province d'Aceh, situ\u00e9e \u00e0 l'extr\u00eame nord de l'\u00eele de Sumatra et qui est reconnue pour sa production de caf\u00e9 Arabica. Cette r\u00e9gion montagneuse de Sumatra abrite environ 100 000 petits producteurs qui cultivent le caf\u00e9 sur des parcelles moyennes","twitter:image":"https:\/\/livelihoods.eu\/wp-content\/uploads\/2025\/01\/LOGO-LIVELIHOODS-RVB_full_color_horizontal.png"},"aioseo_meta_data":{"post_id":"18539","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2025-02-04 04:52:08","updated":"2025-06-18 13:26:07","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/livelihoods.eu\/fr\/\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/livelihoods.eu\/category\/blog\/\" title=\"Blog\">Blog<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tL\u2019agroforesterie pour r\u00e9concilier la nature et le caf\u00e9\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/livelihoods.eu\/fr\/"},{"label":"Blog","link":"https:\/\/livelihoods.eu\/category\/blog\/"},{"label":"L&rsquo;agroforesterie pour r\u00e9concilier la nature et le caf\u00e9","link":"https:\/\/livelihoods.eu\/fr\/when-agroforestry-meets-quality-coffee-in-aceh-north-sumatra\/"}],"_links":{"self":[{"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/posts\/18539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/comments?post=18539"}],"version-history":[{"count":6,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/posts\/18539\/revisions"}],"predecessor-version":[{"id":18609,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/posts\/18539\/revisions\/18609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/media\/18528"}],"wp:attachment":[{"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/media?parent=18539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/categories?post=18539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/livelihoods.eu\/fr\/wp-json\/wp\/v2\/tags?post=18539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}